{"id":255,"count":1,"description":"","link":"https:\/\/www.bottegaspa.com\/en\/tag_blog\/alexander-moscato-grappa-2\/","name":"Alexander Moscato Grappa","slug":"alexander-moscato-grappa-2","taxonomy":"tag_blog","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alexander Moscato Grappa Archivi - Bottega spa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bottegaspa.com\/en\/wp-json\/wp\/v2\/tag_blog\/255\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alexander Moscato Grappa Archivi - Bottega spa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bottegaspa.com\/en\/tag_blog\/alexander-moscato-grappa-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Bottega spa\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bottegaspa.com\/wp-content\/uploads\/2018\/11\/Bottega_spa_logo-new-scroll.png\" \/>\n\t<meta property=\"og:image:width\" content=\"219\" \/>\n\t<meta property=\"og:image:height\" content=\"96\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@BottegaSpa\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.bottegaspa.com\\\/en\\\/tag_blog\\\/alexander-moscato-grappa-2\\\/\",\"url\":\"https:\\\/\\\/www.bottegaspa.com\\\/en\\\/tag_blog\\\/alexander-moscato-grappa-2\\\/\",\"name\":\"Alexander Moscato Grappa Archivi - Bottega spa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bottegaspa.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bottegaspa.com\\\/en\\\/tag_blog\\\/alexander-moscato-grappa-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bottegaspa.com\\\/en\\\/tag_blog\\\/alexander-moscato-grappa-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.bottegaspa.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alexander Moscato Grappa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bottegaspa.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.bottegaspa.com\\\/en\\\/\",\"name\":\"Bottega spa\",\"description\":\"Bottega spa\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.bottegaspa.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bottegaspa.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.bottegaspa.com\\\/en\\\/#organization\",\"name\":\"Bottega spa\",\"url\":\"https:\\\/\\\/www.bottegaspa.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.bottegaspa.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.bottegaspa.com\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/Bottega_spa_logo-new-scroll.png\",\"contentUrl\":\"https:\\\/\\\/www.bottegaspa.com\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/Bottega_spa_logo-new-scroll.png\",\"width\":219,\"height\":96,\"caption\":\"Bottega spa\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bottegaspa.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/BottegaGoldOfficial\\\/\",\"https:\\\/\\\/x.com\\\/BottegaSpa\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/distilleria-bottega\\\/\",\"https:\\\/\\\/www.youtube.com\\\/DistilleriaBottega\",\"https:\\\/\\\/www.instagram.com\\\/bottegagold\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alexander Moscato Grappa Archivi - Bottega spa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bottegaspa.com\/en\/wp-json\/wp\/v2\/tag_blog\/255","og_locale":"en_US","og_type":"article","og_title":"Alexander Moscato Grappa Archivi - Bottega spa","og_url":"https:\/\/www.bottegaspa.com\/en\/tag_blog\/alexander-moscato-grappa-2\/","og_site_name":"Bottega spa","og_image":[{"width":219,"height":96,"url":"https:\/\/www.bottegaspa.com\/wp-content\/uploads\/2018\/11\/Bottega_spa_logo-new-scroll.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@BottegaSpa","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.bottegaspa.com\/en\/tag_blog\/alexander-moscato-grappa-2\/","url":"https:\/\/www.bottegaspa.com\/en\/tag_blog\/alexander-moscato-grappa-2\/","name":"Alexander Moscato Grappa Archivi - Bottega spa","isPartOf":{"@id":"https:\/\/www.bottegaspa.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.bottegaspa.com\/en\/tag_blog\/alexander-moscato-grappa-2\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.bottegaspa.com\/en\/tag_blog\/alexander-moscato-grappa-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bottegaspa.com\/en\/"},{"@type":"ListItem","position":2,"name":"Alexander Moscato Grappa"}]},{"@type":"WebSite","@id":"https:\/\/www.bottegaspa.com\/en\/#website","url":"https:\/\/www.bottegaspa.com\/en\/","name":"Bottega spa","description":"Bottega spa","publisher":{"@id":"https:\/\/www.bottegaspa.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bottegaspa.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.bottegaspa.com\/en\/#organization","name":"Bottega spa","url":"https:\/\/www.bottegaspa.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.bottegaspa.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.bottegaspa.com\/wp-content\/uploads\/2018\/11\/Bottega_spa_logo-new-scroll.png","contentUrl":"https:\/\/www.bottegaspa.com\/wp-content\/uploads\/2018\/11\/Bottega_spa_logo-new-scroll.png","width":219,"height":96,"caption":"Bottega spa"},"image":{"@id":"https:\/\/www.bottegaspa.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/BottegaGoldOfficial\/","https:\/\/x.com\/BottegaSpa","https:\/\/www.linkedin.com\/company\/distilleria-bottega\/","https:\/\/www.youtube.com\/DistilleriaBottega","https:\/\/www.instagram.com\/bottegagold\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.bottegaspa.com\/en\/wp-json\/wp\/v2\/tag_blog\/255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bottegaspa.com\/en\/wp-json\/wp\/v2\/tag_blog"}],"about":[{"href":"https:\/\/www.bottegaspa.com\/en\/wp-json\/wp\/v2\/taxonomies\/tag_blog"}]}}